{"id":60350,"date":"2019-08-26T15:19:33","date_gmt":"2019-08-26T15:19:33","guid":{"rendered":"https:\/\/travelqa.com\/%e7%91%9e%e5%85%b8%e9%a9%bb%e4%bd%90%e6%b2%bb%e4%ba%9a%e5%b7%9e%e7%ac%ac%e6%af%94%e5%88%a9%e6%96%af%e5%a4%a7%e4%bd%bf%e9%a6%86\/"},"modified":"2019-08-26T15:19:33","modified_gmt":"2019-08-26T15:19:33","slug":"%e7%91%9e%e5%85%b8%e9%a9%bb%e4%bd%90%e6%b2%bb%e4%ba%9a%e5%b7%9e%e7%ac%ac%e6%af%94%e5%88%a9%e6%96%af%e5%a4%a7%e4%bd%bf%e9%a6%86","status":"publish","type":"post","link":"https:\/\/travelqa.com\/zh-hans\/%e7%91%9e%e5%85%b8%e9%a9%bb%e4%bd%90%e6%b2%bb%e4%ba%9a%e5%b7%9e%e7%ac%ac%e6%af%94%e5%88%a9%e6%96%af%e5%a4%a7%e4%bd%bf%e9%a6%86\/","title":{"rendered":"\u745e\u5178\u9a7b\u4f50\u6cbb\u4e9a\u5dde\u7b2c\u6bd4\u5229\u65af\u5927\u4f7f\u9986"},"content":{"rendered":"<div id=\"trave-2227567153\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u745e\u5178\u5927\u4f7f\u9986\u8be6\u7ec6\u4fe1\u606f\u5728\u4f50\u6cbb\u4e9a\u5dde\u7b2c\u6bd4\u5229\u65af<\/h3>\n<p><strong><br \/>\n\u5730\u5740:<\/strong><br \/>\n\u7b2c\u6bd4\u5229\u65af<br \/>\n\u683c\u9c81\u5409\u4e9a<br \/>\n<strong><br \/>\n\u5927\u4f7f:<\/strong><br \/>\n<strong>\u7535\u8bdd:<\/strong> (+995) 32 255 03 20<br \/>\n<strong>\u4f20\u771f:<\/strong><br \/>\n<strong>\u7535\u5b50\u90ae\u4ef6:<\/strong><br \/>\n<strong>\u7f51\u7ad9:<\/strong> <\/p>\n<p><strong>\u5de5\u4f5c\u65f6\u95f4:<\/strong> \u661f\u671f\u4e00\uff0c\u661f\u671f\u4e8c\uff1a14<br \/>\n\uff1a00-16\uff1a00\u661f\u671f\u4e09\u81f3\u661f\u671f\u4e94\uff1a09\uff1a30-12\uff1a30<\/p>\n<div id=\"trave-1130302867\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u745e\u5178\u5927\u4f7f\u9986\u8be6\u7ec6\u4fe1\u606f\u5728\u4f50\u6cbb\u4e9a\u5dde\u7b2c\u6bd4\u5229\u65af \u5730\u5740: \u7b2c\u6bd4\u5229\u65af \u683c\u9c81\u5409\u4e9a \u5927\u4f7f: \u7535\u8bdd: (+995) 32 255  [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10068,9491,9097,9098],"tags":[9044],"class_list":["post-60350","post","type-post","status-publish","format-standard","hentry","category-10068","category-9491","category-9097","category-9098","tag-9044"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/zh-hans\/wp-json\/wp\/v2\/posts\/60350"}],"collection":[{"href":"https:\/\/travelqa.com\/zh-hans\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/zh-hans\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/zh-hans\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/zh-hans\/wp-json\/wp\/v2\/comments?post=60350"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/zh-hans\/wp-json\/wp\/v2\/posts\/60350\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=60350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/zh-hans\/wp-json\/wp\/v2\/categories?post=60350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/zh-hans\/wp-json\/wp\/v2\/tags?post=60350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}