{"id":21360,"count":30,"description":"","link":"https:\/\/travelqa.com\/ru\/list\/%d0%a2%d0%b0%d0%b9%d0%b2%d0%b0%d0%bd%d1%8c\/%d0%a2%d0%b0%d0%b9%d0%b2%d0%b0%d0%bd%d1%8c%d1%81%d0%ba%d0%b8%d0%b5-%d1%82%d0%be%d1%80%d0%b3%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b5%d0%b4%d1%81%d1%82%d0%b0%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d1%81\/","name":"\u0422\u0430\u0439\u0432\u0430\u043d\u044c\u0441\u043a\u0438\u0435 \u0442\u043e\u0440\u0433\u043e\u0432\u044b\u0435 \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u0438\u0442\u0435\u043b\u044c\u0441\u0442\u0432\u0430","slug":"%d0%a2%d0%b0%d0%b9%d0%b2%d0%b0%d0%bd%d1%8c%d1%81%d0%ba%d0%b8%d0%b5-%d1%82%d0%be%d1%80%d0%b3%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b5%d0%b4%d1%81%d1%82%d0%b0%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d1%81","taxonomy":"category","parent":21245,"meta":[],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ru\/wp-json\/wp\/v2\/categories\/21360"}],"collection":[{"href":"https:\/\/travelqa.com\/ru\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/travelqa.com\/ru\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ru\/wp-json\/wp\/v2\/categories\/21245"}],"wp:post_type":[{"href":"https:\/\/travelqa.com\/ru\/wp-json\/wp\/v2\/posts?categories=21360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}