{"id":184893,"date":"2019-09-02T18:11:33","date_gmt":"2019-09-02T18:11:33","guid":{"rendered":"https:\/\/travelqa.com\/%e3%82%a4%e3%82%ae%e3%83%aa%e3%82%b9%e3%80%81%e3%83%ad%e3%83%b3%e3%83%89%e3%83%b3%e3%81%ae%e3%83%95%e3%82%a9%e3%83%bc%e3%82%af%e3%83%a9%e3%83%b3%e3%83%89%e8%ab%b8%e5%b3%b6%e6%94%bf%e5%ba%9c%e4%ba%8b\/"},"modified":"2019-09-02T18:11:33","modified_gmt":"2019-09-02T18:11:33","slug":"%e3%82%a4%e3%82%ae%e3%83%aa%e3%82%b9%e3%80%81%e3%83%ad%e3%83%b3%e3%83%89%e3%83%b3%e3%81%ae%e3%83%95%e3%82%a9%e3%83%bc%e3%82%af%e3%83%a9%e3%83%b3%e3%83%89%e8%ab%b8%e5%b3%b6%e6%94%bf%e5%ba%9c%e4%ba%8b","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ja\/%e3%82%a4%e3%82%ae%e3%83%aa%e3%82%b9%e3%80%81%e3%83%ad%e3%83%b3%e3%83%89%e3%83%b3%e3%81%ae%e3%83%95%e3%82%a9%e3%83%bc%e3%82%af%e3%83%a9%e3%83%b3%e3%83%89%e8%ab%b8%e5%b3%b6%e6%94%bf%e5%ba%9c%e4%ba%8b\/","title":{"rendered":"\u30a4\u30ae\u30ea\u30b9\u3001\u30ed\u30f3\u30c9\u30f3\u306e\u30d5\u30a9\u30fc\u30af\u30e9\u30f3\u30c9\u8af8\u5cf6\u653f\u5e9c\u4e8b\u52d9\u6240"},"content":{"rendered":"<div id=\"trave-1505949536\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u30a4\u30ae\u30ea\u30b9\u3001\u30ed\u30f3\u30c9\u30f3\u306e\u30d5\u30a9\u30fc\u30af\u30e9\u30f3\u30c9\u8af8\u5cf6\u653f\u5e9c\u4e8b\u52d9\u6240\u306e\u8a73\u7d30<\/h3>\n<p><strong><br \/>\n\u4f4f\u6240:<\/strong><br \/>\n\u30d5\u30a9\u30fc\u30af\u30e9\u30f3\u30c9\u30cf\u30a6\u30b9<br \/>\n14\u3001\u30d6\u30ed\u30fc\u30c9\u30a6\u30a7\u30a4<br \/>\n\u30ed\u30f3\u30c9\u30f3\u3001SW1H 0BH<br \/>\n\u30a4\u30ae\u30ea\u30b9<br \/>\n<strong><br \/>\n\u5927\u4f7f:<\/strong> \u30b9\u30ad\u30fc\u30fb\u30ad\u30e3\u30e1\u30ed\u30f3\u4ee3\u8868<br \/>\n<strong>\u96fb\u8a71:<\/strong> (+44) 20 7222 2542<br \/>\n<strong>\u30d5\u30a1\u30c3\u30af\u30b9:<\/strong> (+44) 20 7222 2375<br \/>\n<strong>E\u30e1\u30fc\u30eb:<\/strong> representative@falklands.gov.fk<br \/>\n<strong>\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8:<\/strong> <\/p>\n<p><strong>\u55b6\u696d\u6642\u9593:<\/strong> <\/p>\n<div id=\"trave-3519662235\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u30a4\u30ae\u30ea\u30b9\u3001\u30ed\u30f3\u30c9\u30f3\u306e\u30d5\u30a9\u30fc\u30af\u30e9\u30f3\u30c9\u8af8\u5cf6\u653f\u5e9c\u4e8b\u52d9\u6240\u306e\u8a73\u7d30 \u4f4f\u6240: \u30d5\u30a9\u30fc\u30af\u30e9\u30f3\u30c9\u30cf\u30a6\u30b9 14\u3001\u30d6\u30ed\u30fc\u30c9\u30a6\u30a7\u30a4 \u30ed\u30f3\u30c9\u30f3\u3001SW1H 0BH \u30a4\u30ae\u30ea\u30b9 \u5927\u4f7f: \u30b9\u30ad\u30fc\u30fb\u30ad\u30e3\u30e1\u30ed\u30f3\u4ee3\u8868 \u96fb\u8a71: (+44) 20 7222 254 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17197,19102,18268,19104],"tags":[17964],"class_list":["post-184893","post","type-post","status-publish","format-standard","hentry","category-17197","category-19102","category-18268","category-19104","tag-17964"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/184893"}],"collection":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/comments?post=184893"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/184893\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/media?parent=184893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/categories?post=184893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/tags?post=184893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}