{"id":178445,"date":"2019-09-02T15:01:16","date_gmt":"2019-09-02T15:01:16","guid":{"rendered":"https:\/\/travelqa.com\/%e3%83%91%e3%83%8a%e3%83%9e%e3%80%81%e3%83%91%e3%83%8a%e3%83%9e%e3%82%b7%e3%83%86%e3%82%a3%e3%81%ae%e3%83%ac%e3%83%90%e3%83%8e%e3%83%b3%e7%b7%8f%e9%a0%98%e4%ba%8b%e9%a4%a8\/"},"modified":"2019-09-02T15:01:16","modified_gmt":"2019-09-02T15:01:16","slug":"%e3%83%91%e3%83%8a%e3%83%9e%e3%80%81%e3%83%91%e3%83%8a%e3%83%9e%e3%82%b7%e3%83%86%e3%82%a3%e3%81%ae%e3%83%ac%e3%83%90%e3%83%8e%e3%83%b3%e7%b7%8f%e9%a0%98%e4%ba%8b%e9%a4%a8","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ja\/%e3%83%91%e3%83%8a%e3%83%9e%e3%80%81%e3%83%91%e3%83%8a%e3%83%9e%e3%82%b7%e3%83%86%e3%82%a3%e3%81%ae%e3%83%ac%e3%83%90%e3%83%8e%e3%83%b3%e7%b7%8f%e9%a0%98%e4%ba%8b%e9%a4%a8\/","title":{"rendered":"\u30d1\u30ca\u30de\u3001\u30d1\u30ca\u30de\u30b7\u30c6\u30a3\u306e\u30ec\u30d0\u30ce\u30f3\u7dcf\u9818\u4e8b\u9928"},"content":{"rendered":"<div id=\"trave-2173870735\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u30d1\u30ca\u30de\u30b7\u30c6\u30a3\u3001\u30d1\u30ca\u30de\u306e\u30ec\u30d0\u30ce\u30f3\u9818\u4e8b\u9928\u306e\u4e00\u822c\u7684\u306a\u8a73\u7d30<\/h3>\n<p><strong><br \/>\n\u4f4f\u6240:<\/strong><br \/>\nPort de Lesseps\u3001Edifio El Jasa<br \/>\n\u30d1\u30ca\u30de\u30b7\u30c6\u30a3<br \/>\n\u30d1\u30ca\u30de<br \/>\n<strong><br \/>\n\u5927\u4f7f:<\/strong> Faozi Hachem\u3001\u540d\u8a89\u7dcf\u9818\u4e8b<br \/>\n<strong>\u96fb\u8a71:<\/strong> 433-1522<br \/>\n 433-1028<br \/>\n<strong>\u30d5\u30a1\u30c3\u30af\u30b9:<\/strong> 433-1522<br \/>\n<strong>E\u30e1\u30fc\u30eb:<\/strong><br \/>\n<strong>\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8:<\/strong> <\/p>\n<p><strong>\u55b6\u696d\u6642\u9593:<\/strong> <\/p>\n<div id=\"trave-3597894156\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u30d1\u30ca\u30de\u30b7\u30c6\u30a3\u3001\u30d1\u30ca\u30de\u306e\u30ec\u30d0\u30ce\u30f3\u9818\u4e8b\u9928\u306e\u4e00\u822c\u7684\u306a\u8a73\u7d30 \u4f4f\u6240: Port de Lesseps\u3001Edifio El Jasa \u30d1\u30ca\u30de\u30b7\u30c6\u30a3 \u30d1\u30ca\u30de \u5927\u4f7f: Faozi Hachem\u3001\u540d\u8a89\u7dcf\u9818\u4e8b \u96fb\u8a71: 433-1522 43 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17592,18785,17426,17741],"tags":[17165],"class_list":["post-178445","post","type-post","status-publish","format-standard","hentry","category-17592","category-18785","category-17426","category-17741","tag-17165"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/178445"}],"collection":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/comments?post=178445"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/178445\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/media?parent=178445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/categories?post=178445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/tags?post=178445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}