{"id":174734,"date":"2019-09-02T13:03:11","date_gmt":"2019-09-02T13:03:11","guid":{"rendered":"https:\/\/travelqa.com\/%e3%82%ad%e3%83%ab%e3%82%ae%e3%82%b9%e3%82%bf%e3%83%b3%e3%80%81%e3%83%93%e3%82%b7%e3%83%a5%e3%82%b1%e3%82%af%e3%81%ae%e3%83%91%e3%82%ad%e3%82%b9%e3%82%bf%e3%83%b3%e5%a4%a7%e4%bd%bf%e9%a4%a8\/"},"modified":"2019-09-02T13:03:11","modified_gmt":"2019-09-02T13:03:11","slug":"%e3%82%ad%e3%83%ab%e3%82%ae%e3%82%b9%e3%82%bf%e3%83%b3%e3%80%81%e3%83%93%e3%82%b7%e3%83%a5%e3%82%b1%e3%82%af%e3%81%ae%e3%83%91%e3%82%ad%e3%82%b9%e3%82%bf%e3%83%b3%e5%a4%a7%e4%bd%bf%e9%a4%a8","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ja\/%e3%82%ad%e3%83%ab%e3%82%ae%e3%82%b9%e3%82%bf%e3%83%b3%e3%80%81%e3%83%93%e3%82%b7%e3%83%a5%e3%82%b1%e3%82%af%e3%81%ae%e3%83%91%e3%82%ad%e3%82%b9%e3%82%bf%e3%83%b3%e5%a4%a7%e4%bd%bf%e9%a4%a8\/","title":{"rendered":"\u30ad\u30eb\u30ae\u30b9\u30bf\u30f3\u3001\u30d3\u30b7\u30e5\u30b1\u30af\u306e\u30d1\u30ad\u30b9\u30bf\u30f3\u5927\u4f7f\u9928"},"content":{"rendered":"<div id=\"trave-1617395612\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u30ad\u30eb\u30ae\u30b9\u30bf\u30f3\u3001\u30d3\u30b7\u30e5\u30b1\u30af\u306e\u30d1\u30ad\u30b9\u30bf\u30f3\u5927\u4f7f\u9928\u8a73\u7d30<\/h3>\n<p><strong><br \/>\n\u4f4f\u6240:<\/strong><br \/>\n\u30d3\u30b7\u30e5\u30b1\u30af720040<br \/>\n\u30ad\u30eb\u30ae\u30b9\u30bf\u30f3<br \/>\n<strong><br \/>\n\u5927\u4f7f:<\/strong><br \/>\n<strong>\u96fb\u8a71:<\/strong> (+996) (312) 37 39 01 to 04<br \/>\n<strong>\u30d5\u30a1\u30c3\u30af\u30b9:<\/strong> (+996) (312) 37 39 05<br \/>\n<strong>E\u30e1\u30fc\u30eb:<\/strong><br \/>\n<strong>\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8:<\/strong> <\/p>\n<p><strong>\u55b6\u696d\u6642\u9593:<\/strong> <\/p>\n<div id=\"trave-3519921065\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u30ad\u30eb\u30ae\u30b9\u30bf\u30f3\u3001\u30d3\u30b7\u30e5\u30b1\u30af\u306e\u30d1\u30ad\u30b9\u30bf\u30f3\u5927\u4f7f\u9928\u8a73\u7d30 \u4f4f\u6240: \u30d3\u30b7\u30e5\u30b1\u30af720040 \u30ad\u30eb\u30ae\u30b9\u30bf\u30f3 \u5927\u4f7f: \u96fb\u8a71: (+996) (312) 37 39 01 to 04 \u30d5\u30a1\u30c3\u30af\u30b9: (+996) (312) 37 39 0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17233,18551,17200,17202],"tags":[17151],"class_list":["post-174734","post","type-post","status-publish","format-standard","hentry","category-17233","category-18551","category-17200","category-17202","tag-17151"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/174734"}],"collection":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/comments?post=174734"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/174734\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/media?parent=174734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/categories?post=174734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/tags?post=174734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}