{"id":172485,"date":"2019-09-02T12:05:58","date_gmt":"2019-09-02T12:05:58","guid":{"rendered":"https:\/\/travelqa.com\/%e3%82%a4%e3%83%a9%e3%82%af%e3%80%81%e3%83%90%e3%82%b0%e3%83%80%e3%83%83%e3%83%89%e3%81%ae%e9%9f%93%e5%9b%bd%e5%a4%a7%e4%bd%bf%e9%a4%a8\/"},"modified":"2019-09-02T12:05:58","modified_gmt":"2019-09-02T12:05:58","slug":"%e3%82%a4%e3%83%a9%e3%82%af%e3%80%81%e3%83%90%e3%82%b0%e3%83%80%e3%83%83%e3%83%89%e3%81%ae%e9%9f%93%e5%9b%bd%e5%a4%a7%e4%bd%bf%e9%a4%a8","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ja\/%e3%82%a4%e3%83%a9%e3%82%af%e3%80%81%e3%83%90%e3%82%b0%e3%83%80%e3%83%83%e3%83%89%e3%81%ae%e9%9f%93%e5%9b%bd%e5%a4%a7%e4%bd%bf%e9%a4%a8\/","title":{"rendered":"\u30a4\u30e9\u30af\u3001\u30d0\u30b0\u30c0\u30c3\u30c9\u306e\u97d3\u56fd\u5927\u4f7f\u9928"},"content":{"rendered":"<div id=\"trave-3722060735\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u30d0\u30b0\u30c0\u30c3\u30c9\u3001\u30a4\u30e9\u30af\u306e\u97d3\u56fd\u5927\u4f7f\u9928\u306e\u8a73\u7d30<\/h3>\n<p><strong><br \/>\n\u4f4f\u6240:<\/strong><br \/>\n\u30d0\u30b0\u30c0\u30c3\u30c9<br \/>\n\u30a4\u30e9\u30af<br \/>\n<strong><br \/>\n\u5927\u4f7f:<\/strong><br \/>\n<strong>\u96fb\u8a71:<\/strong> (+964) 77-0725 2006<br \/>\n(+964) 77-0811-7889<br \/>\n<strong>\u30d5\u30a1\u30c3\u30af\u30b9:<\/strong><br \/>\n<strong>E\u30e1\u30fc\u30eb:<\/strong><br \/>\n<strong>\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8:<\/strong> <\/p>\n<p><strong>\u55b6\u696d\u6642\u9593:<\/strong> \u65e5\u66dc\u65e5\u304b\u3089\u6728\u66dc\u65e5\uff1a08\uff1a00-16\uff1a00<\/p>\n<div id=\"trave-2032745285\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u30d0\u30b0\u30c0\u30c3\u30c9\u3001\u30a4\u30e9\u30af\u306e\u97d3\u56fd\u5927\u4f7f\u9928\u306e\u8a73\u7d30 \u4f4f\u6240: \u30d0\u30b0\u30c0\u30c3\u30c9 \u30a4\u30e9\u30af \u5927\u4f7f: \u96fb\u8a71: (+964) 77-0725 2006 (+964) 77-0811-7889 \u30d5\u30a1\u30c3\u30af\u30b9: E\u30e1\u30fc\u30eb: \u30a6\u30a7\u30d6\u30b5\u30a4\u30c8: \u55b6\u696d\u6642\u9593: \u65e5\u66dc [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17189,18463,17229,17230],"tags":[17151],"class_list":["post-172485","post","type-post","status-publish","format-standard","hentry","category-17189","category-18463","category-17229","category-17230","tag-17151"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/172485"}],"collection":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/comments?post=172485"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/172485\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/media?parent=172485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/categories?post=172485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/tags?post=172485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}