{"id":172063,"date":"2019-09-02T11:54:04","date_gmt":"2019-09-02T11:54:04","guid":{"rendered":"https:\/\/travelqa.com\/%e3%82%a4%e3%83%b3%e3%83%89%e3%80%81%e3%83%a0%e3%83%b3%e3%83%90%e3%82%a4%e3%81%ae%e5%8f%b0%e6%b9%be%e8%b2%bf%e6%98%93%e4%ba%8b%e5%8b%99%e6%89%80\/"},"modified":"2019-09-02T11:54:04","modified_gmt":"2019-09-02T11:54:04","slug":"%e3%82%a4%e3%83%b3%e3%83%89%e3%80%81%e3%83%a0%e3%83%b3%e3%83%90%e3%82%a4%e3%81%ae%e5%8f%b0%e6%b9%be%e8%b2%bf%e6%98%93%e4%ba%8b%e5%8b%99%e6%89%80","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ja\/%e3%82%a4%e3%83%b3%e3%83%89%e3%80%81%e3%83%a0%e3%83%b3%e3%83%90%e3%82%a4%e3%81%ae%e5%8f%b0%e6%b9%be%e8%b2%bf%e6%98%93%e4%ba%8b%e5%8b%99%e6%89%80\/","title":{"rendered":"\u30a4\u30f3\u30c9\u3001\u30e0\u30f3\u30d0\u30a4\u306e\u53f0\u6e7e\u8cbf\u6613\u4e8b\u52d9\u6240"},"content":{"rendered":"<div id=\"trave-650859845\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u30a4\u30f3\u30c9\u3001\u30e0\u30f3\u30d0\u30a4\u306e\u53f0\u6e7e\u8cbf\u6613\u4e8b\u52d9\u6240\u306e\u8a73\u7d30<\/h3>\n<p><strong><br \/>\n\u4f4f\u6240:<\/strong><br \/>\nMVIRDC\u4e16\u754c\u8cbf\u6613\u30bb\u30f3\u30bf\u30fc<br \/>\n8\u53f7\u6a5f\u300111\u968e\u3001\u30bb\u30f3\u30bf\u30fc1<br \/>\n\u30ab\u30d5\u30d1\u30ec\u30fc\u30c9<br \/>\n\u30e0\u30f3\u30d0\u30a4400 005<br \/>\n\u30a4\u30f3\u30c9<br \/>\n<strong><br \/>\n\u5927\u4f7f:<\/strong><br \/>\n<strong>\u96fb\u8a71:<\/strong> (+91) 22 2216 3074<br \/>\n<strong>\u30d5\u30a1\u30c3\u30af\u30b9:<\/strong> (+91) 22 2216 3078<br \/>\n<strong>E\u30e1\u30fc\u30eb:<\/strong> mumbai@taitra.org.tw<br \/>\n<strong>\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8:<\/strong> mumbai.taiwantrade.com<\/p>\n<p><strong>\u55b6\u696d\u6642\u9593:<\/strong> <\/p>\n<div id=\"trave-3088303825\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u30a4\u30f3\u30c9\u3001\u30e0\u30f3\u30d0\u30a4\u306e\u53f0\u6e7e\u8cbf\u6613\u4e8b\u52d9\u6240\u306e\u8a73\u7d30 \u4f4f\u6240: MVIRDC\u4e16\u754c\u8cbf\u6613\u30bb\u30f3\u30bf\u30fc 8\u53f7\u6a5f\u300111\u968e\u3001\u30bb\u30f3\u30bf\u30fc1 \u30ab\u30d5\u30d1\u30ec\u30fc\u30c9 \u30e0\u30f3\u30d0\u30a4400 005 \u30a4\u30f3\u30c9 \u5927\u4f7f: \u96fb\u8a71: (+91) 22 2216 3074 \u30d5\u30a1\u30c3\u30af\u30b9:  [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17182,18428,9459,17685],"tags":[17686],"class_list":["post-172063","post","type-post","status-publish","format-standard","hentry","category-17182","category-18428","category-9459","category-17685","tag-17686"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/172063"}],"collection":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/comments?post=172063"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/172063\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/media?parent=172063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/categories?post=172063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/tags?post=172063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}