{"id":170553,"date":"2019-09-02T11:10:31","date_gmt":"2019-09-02T11:10:31","guid":{"rendered":"https:\/\/travelqa.com\/%e3%82%b8%e3%83%96%e3%83%a9%e3%83%ab%e3%82%bf%e3%83%ab%e3%80%81%e3%82%b8%e3%83%96%e3%83%a9%e3%83%ab%e3%82%bf%e3%83%ab%e3%81%ae%e3%83%95%e3%83%a9%e3%83%b3%e3%82%b9%e9%a0%98%e4%ba%8b%e9%a4%a8\/"},"modified":"2019-09-02T11:10:31","modified_gmt":"2019-09-02T11:10:31","slug":"%e3%82%b8%e3%83%96%e3%83%a9%e3%83%ab%e3%82%bf%e3%83%ab%e3%80%81%e3%82%b8%e3%83%96%e3%83%a9%e3%83%ab%e3%82%bf%e3%83%ab%e3%81%ae%e3%83%95%e3%83%a9%e3%83%b3%e3%82%b9%e9%a0%98%e4%ba%8b%e9%a4%a8","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ja\/%e3%82%b8%e3%83%96%e3%83%a9%e3%83%ab%e3%82%bf%e3%83%ab%e3%80%81%e3%82%b8%e3%83%96%e3%83%a9%e3%83%ab%e3%82%bf%e3%83%ab%e3%81%ae%e3%83%95%e3%83%a9%e3%83%b3%e3%82%b9%e9%a0%98%e4%ba%8b%e9%a4%a8\/","title":{"rendered":"\u30b8\u30d6\u30e9\u30eb\u30bf\u30eb\u3001\u30b8\u30d6\u30e9\u30eb\u30bf\u30eb\u306e\u30d5\u30e9\u30f3\u30b9\u9818\u4e8b\u9928"},"content":{"rendered":"<div id=\"trave-506155875\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u30b8\u30d6\u30e9\u30eb\u30bf\u30eb\u3001\u30b8\u30d6\u30e9\u30eb\u30bf\u30eb\u306e\u30d5\u30e9\u30f3\u30b9\u9818\u4e8b\u9928\u306e\u8a73\u7d30<\/h3>\n<p><strong><br \/>\n\u4f4f\u6240:<\/strong><br \/>\nICC\u30d3\u30eb<br \/>\n2A Main Street<br \/>\nP.O.Box 557<br \/>\n\u30b8\u30d6\u30e9\u30eb\u30bf\u30eb<br \/>\n<strong><br \/>\n\u5927\u4f7f:<\/strong> \u30d4\u30a8\u30fc\u30eb\u30fb\u30d5\u30a1\u30e4\u30fc\u30c9\u540d\u8a89\u9818\u4e8b<br \/>\n<strong>\u96fb\u8a71:<\/strong> (+350) 200 48070<br \/>\n<strong>\u30d5\u30a1\u30c3\u30af\u30b9:<\/strong> (+350) 200 76253<br \/>\n<strong>E\u30e1\u30fc\u30eb:<\/strong> france@cbb.gi<br \/>\n<strong>\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8:<\/strong> <\/p>\n<p><strong>\u55b6\u696d\u6642\u9593:<\/strong> 10.30-12.30<\/p>\n<div id=\"trave-1630356564\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u30b8\u30d6\u30e9\u30eb\u30bf\u30eb\u3001\u30b8\u30d6\u30e9\u30eb\u30bf\u30eb\u306e\u30d5\u30e9\u30f3\u30b9\u9818\u4e8b\u9928\u306e\u8a73\u7d30 \u4f4f\u6240: ICC\u30d3\u30eb 2A Main Street P.O.Box 557 \u30b8\u30d6\u30e9\u30eb\u30bf\u30eb \u5927\u4f7f: \u30d4\u30a8\u30fc\u30eb\u30fb\u30d5\u30a1\u30e4\u30fc\u30c9\u540d\u8a89\u9818\u4e8b \u96fb\u8a71: (+350) 200 48070 \u30d5 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17896,18348,17179,17514],"tags":[17154],"class_list":["post-170553","post","type-post","status-publish","format-standard","hentry","category-17896","category-18348","category-17179","category-17514","tag-17154"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/170553"}],"collection":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/comments?post=170553"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/170553\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/media?parent=170553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/categories?post=170553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/tags?post=170553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}