{"id":165069,"date":"2019-09-02T08:43:27","date_gmt":"2019-09-02T08:43:27","guid":{"rendered":"https:\/\/travelqa.com\/%e3%82%ab%e3%83%a1%e3%83%ab%e3%83%bc%e3%83%b3%e3%80%81%e3%83%89%e3%82%a5%e3%82%a2%e3%83%a9%e3%81%ae%e3%83%81%e3%82%a7%e3%82%b3%e5%85%b1%e5%92%8c%e5%9b%bd%e9%a0%98%e4%ba%8b%e9%a4%a8\/"},"modified":"2019-09-02T08:43:27","modified_gmt":"2019-09-02T08:43:27","slug":"%e3%82%ab%e3%83%a1%e3%83%ab%e3%83%bc%e3%83%b3%e3%80%81%e3%83%89%e3%82%a5%e3%82%a2%e3%83%a9%e3%81%ae%e3%83%81%e3%82%a7%e3%82%b3%e5%85%b1%e5%92%8c%e5%9b%bd%e9%a0%98%e4%ba%8b%e9%a4%a8","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ja\/%e3%82%ab%e3%83%a1%e3%83%ab%e3%83%bc%e3%83%b3%e3%80%81%e3%83%89%e3%82%a5%e3%82%a2%e3%83%a9%e3%81%ae%e3%83%81%e3%82%a7%e3%82%b3%e5%85%b1%e5%92%8c%e5%9b%bd%e9%a0%98%e4%ba%8b%e9%a4%a8\/","title":{"rendered":"\u30ab\u30e1\u30eb\u30fc\u30f3\u3001\u30c9\u30a5\u30a2\u30e9\u306e\u30c1\u30a7\u30b3\u5171\u548c\u56fd\u9818\u4e8b\u9928"},"content":{"rendered":"<div id=\"trave-438882854\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u30c9\u30a5\u30a2\u30e9\u3001\u30ab\u30e1\u30eb\u30fc\u30f3\u306e\u30c1\u30a7\u30b3\u9818\u4e8b\u9928\u306e\u8a73\u7d30<\/h3>\n<p><strong><br \/>\n\u4f4f\u6240:<\/strong><br \/>\n140\u3001rue Dominique Savio primaire<br \/>\nBonapriso<br \/>\nB.P.1511<br \/>\n\u30c9\u30a5\u30a2\u30e9<br \/>\n\u30ab\u30e1\u30eb\u30fc\u30f3<br \/>\n<strong><br \/>\n\u5927\u4f7f:<\/strong> \u30d9\u30e9\u30fb\u30e4\u30d9\u30b3\u3001\u540d\u8a89\u9818\u4e8b<br \/>\n<strong>\u96fb\u8a71:<\/strong> (+237) 69 992 6690<br \/>\n<strong>\u30d5\u30a1\u30c3\u30af\u30b9:<\/strong><br \/>\n<strong>E\u30e1\u30fc\u30eb:<\/strong> douala@honorary.mzv.cz<br \/>\n<strong>\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8:<\/strong> <\/p>\n<p><strong>\u55b6\u696d\u6642\u9593:<\/strong> \u706b\u66dc\u65e5\u3068\u6728\u66dc\u65e5\uff1a09.00-11.00<\/p>\n<div id=\"trave-248683204\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u30c9\u30a5\u30a2\u30e9\u3001\u30ab\u30e1\u30eb\u30fc\u30f3\u306e\u30c1\u30a7\u30b3\u9818\u4e8b\u9928\u306e\u8a73\u7d30 \u4f4f\u6240: 140\u3001rue Dominique Savio primaire Bonapriso B.P.1511 \u30c9\u30a5\u30a2\u30e9 \u30ab\u30e1\u30eb\u30fc\u30f3 \u5927\u4f7f: \u30d9\u30e9\u30fb\u30e4\u30d9\u30b3\u3001\u540d\u8a89\u9818\u4e8b \u96fb\u8a71: (+ [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17438,18049,17224,17470],"tags":[17154],"class_list":["post-165069","post","type-post","status-publish","format-standard","hentry","category-17438","category-18049","category-17224","category-17470","tag-17154"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/165069"}],"collection":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/comments?post=165069"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/posts\/165069\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/media?parent=165069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/categories?post=165069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ja\/wp-json\/wp\/v2\/tags?post=165069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}