{"id":97788,"date":"2019-08-27T11:18:02","date_gmt":"2019-08-27T11:18:02","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-du-bresil-a-ljubljana-slovenie\/"},"modified":"2019-08-27T11:18:02","modified_gmt":"2019-08-27T11:18:02","slug":"ambassade-du-bresil-a-ljubljana-slovenie","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-du-bresil-a-ljubljana-slovenie\/","title":{"rendered":"Ambassade du Br\u00e9sil \u00e0 Ljubljana, Slov\u00e9nie"},"content":{"rendered":"<div id=\"trave-271250842\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails de l&rsquo;ambassade du Br\u00e9sil \u00e0 Ljubljana, Slov\u00e9nie<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\n1000 Ljubljana<br \/>\nSlov\u00e9nie<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> Renato Mosca, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+386) 1 244 24 20<br \/>\n<strong>Fax:<\/strong> (+386) 1 244 24 20<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-1711242583\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails de l&rsquo;ambassade du Br\u00e9sil \u00e0 Ljubljana, Slov\u00e9nie Adresse: 1000 Ljubljana Slov\u00e9nie Ambassadeur: Renato Mosca, ambassadeur T\u00e9l\u00e9phone: (+386) 1 244 24 20 Fax: (+386) 1 244 24 20 Email: Site Internet: Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10974,12620,10855,10912],"tags":[10806],"class_list":["post-97788","post","type-post","status-publish","format-standard","hentry","category-ambassades-du-bresil","category-ambassades-en-slovenie","category-bresil","category-la-slovenie","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/97788"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=97788"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/97788\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=97788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=97788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=97788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}