{"id":96618,"date":"2019-08-27T10:51:33","date_gmt":"2019-08-27T10:51:33","guid":{"rendered":"https:\/\/travelqa.com\/bureau-de-lambassade-du-belarus-a-rostov-sur-le-don-russie\/"},"modified":"2019-08-27T10:51:33","modified_gmt":"2019-08-27T10:51:33","slug":"bureau-de-lambassade-du-belarus-a-rostov-sur-le-don-russie","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/bureau-de-lambassade-du-belarus-a-rostov-sur-le-don-russie\/","title":{"rendered":"Bureau de l&rsquo;ambassade du B\u00e9larus \u00e0 Rostov-sur-le-Don, Russie"},"content":{"rendered":"<div id=\"trave-3494483023\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Coordonn\u00e9es de la succursale de l&rsquo;ambassade de Bi\u00e9lorussie \u00e0 Rostov-sur-le-Don, en Russie<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\n344.019 Rostov-on-Don \u00bb<br \/>\nRussie<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong><br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+7) 8632 86 96 90<br \/>\n<strong>Fax:<\/strong> (+7) 8632 86 96 91<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-430862777\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Coordonn\u00e9es de la succursale de l&rsquo;ambassade de Bi\u00e9lorussie \u00e0 Rostov-sur-le-Don, en Russie Adresse: 344.019 Rostov-on-Don \u00bb Russie Ambassadeur: T\u00e9l\u00e9phone: (+7) 8632 86 96 90 Fax: (+7) 8632 86 96 91 Email: Site Internet: Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11167,12532,12531,10804],"tags":[11615],"class_list":["post-96618","post","type-post","status-publish","format-standard","hentry","category-bielorussie","category-branches-de-lambassade-de-bielorussie","category-bureaux-dambassades-en-russie","category-russie","tag-direction-de-lambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/96618"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=96618"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/96618\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=96618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=96618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=96618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}