{"id":95199,"date":"2019-08-27T10:23:29","date_gmt":"2019-08-27T10:23:29","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-la-republique-dominicaine-a-panama-panama\/"},"modified":"2019-08-27T10:23:29","modified_gmt":"2019-08-27T10:23:29","slug":"ambassade-de-la-republique-dominicaine-a-panama-panama","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-la-republique-dominicaine-a-panama-panama\/","title":{"rendered":"Ambassade de la R\u00e9publique dominicaine \u00e0 Panama, Panama"},"content":{"rendered":"<div id=\"trave-4114058619\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails de l&rsquo;ambassade dominicaine \u00e0 Panama, Panama<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nCalle 50 con Calle 56<br \/>\nEdificio F &#038; F Tour (El Tornillo)<br \/>\npiso 26, Oficinas C y D<br \/>\nMarbella<br \/>\nCiudad de Panam\u00e1<br \/>\nPanama<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> C\u00e9sar Augusto Medina Abreu, Charg\u00e9 d&rsquo;Affaires ai<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+507) 394-7813 to 5<br \/>\n<strong>Fax:<\/strong> (+507) 394-7816<br \/>\n<strong>Email:<\/strong> embajadompa@hotmail.com<br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-2983481853\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails de l&rsquo;ambassade dominicaine \u00e0 Panama, Panama Adresse: Calle 50 con Calle 56 Edificio F &#038; F Tour (El Tornillo) piso 26, Oficinas C y D Marbella Ciudad de Panam\u00e1 Panama Ambassadeur: C\u00e9sar Augusto Medina Abreu, Charg\u00e9 d&rsquo;Affaires ai T\u00e9l\u00e9phone: (+507) 394-7813 to 5 Fax: (+507) 394-7816 Email: embajadompa@hotmail.com Site Internet: Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12468,11196,6231,11092],"tags":[10806],"class_list":["post-95199","post","type-post","status-publish","format-standard","hentry","category-ambassades-au-panama","category-ambassades-dominicaines","category-panama","category-republique-dominicaine","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/95199"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=95199"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/95199\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=95199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=95199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=95199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}