{"id":88527,"date":"2019-08-27T08:16:06","date_gmt":"2019-08-27T08:16:06","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-slovaquie-a-new-delhi-inde\/"},"modified":"2019-08-27T08:16:06","modified_gmt":"2019-08-27T08:16:06","slug":"ambassade-de-slovaquie-a-new-delhi-inde","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-slovaquie-a-new-delhi-inde\/","title":{"rendered":"Ambassade de Slovaquie \u00e0 New Delhi, Inde"},"content":{"rendered":"<div id=\"trave-3715760867\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails de l&rsquo;ambassade de Slovaquie \u00e0 New Delhi, Inde<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nChanakyapuri<br \/>\nNew Delhi 110021<br \/>\nInde<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> M. Zigmund Bert\u00f3k, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+91) 11 2687 7941<br \/>\n<strong>Fax:<\/strong> (+91) 11 2687 7941<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> 08h00 &#8211; 16h00<\/p>\n<div id=\"trave-777312497\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails de l&rsquo;ambassade de Slovaquie \u00e0 New Delhi, Inde Adresse: Chanakyapuri New Delhi 110021 Inde Ambassadeur: M. Zigmund Bert\u00f3k, ambassadeur T\u00e9l\u00e9phone: (+91) 11 2687 7941 Fax: (+91) 11 2687 7941 Email: Site Internet: Heures de travail: 08h00 &#8211; 16h00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10931,12090,10833,10930],"tags":[10806],"class_list":["post-88527","post","type-post","status-publish","format-standard","hentry","category-ambassades-de-slovaquie","category-ambassades-en-inde","category-inde","category-slovaquie","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/88527"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=88527"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/88527\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=88527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=88527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=88527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}