{"id":86918,"date":"2019-08-27T07:47:15","date_gmt":"2019-08-27T07:47:15","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-pologne-a-berlin-allemagne\/"},"modified":"2019-08-27T07:47:15","modified_gmt":"2019-08-27T07:47:15","slug":"ambassade-de-pologne-a-berlin-allemagne","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-pologne-a-berlin-allemagne\/","title":{"rendered":"Ambassade de Pologne \u00e0 Berlin, Allemagne"},"content":{"rendered":"<div id=\"trave-2111702241\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails de l&rsquo;ambassade de Pologne \u00e0 Berlin, en Allemagne<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nBerlin 14193<br \/>\nAllemagne<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> M. Andrzej Przylebski, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+49) 30 22 31 31 55<br \/>\n(+49) 30 22 31 32 01\/00 (Consular Section<br \/>\n<strong>Fax:<\/strong> (+49) 30 22 31 31 55<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-1881040587\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails de l&rsquo;ambassade de Pologne \u00e0 Berlin, en Allemagne Adresse: Berlin 14193 Allemagne Ambassadeur: M. Andrzej Przylebski, ambassadeur T\u00e9l\u00e9phone: (+49) 30 22 31 31 55 (+49) 30 22 31 32 01\/00 (Consular Section Fax: (+49) 30 22 31 31 55 Email: Site Internet: Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10820,10959,11975,10958],"tags":[10806],"class_list":["post-86918","post","type-post","status-publish","format-standard","hentry","category-allemagne","category-ambassades-de-pologne","category-ambassades-en-allemagne","category-pologne","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/86918"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=86918"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/86918\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=86918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=86918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=86918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}