{"id":86893,"date":"2019-08-27T07:46:49","date_gmt":"2019-08-27T07:46:49","guid":{"rendered":"https:\/\/travelqa.com\/bureau-de-lambassade-du-kazakhstan-a-bonn-en-allemagne\/"},"modified":"2019-08-27T07:46:49","modified_gmt":"2019-08-27T07:46:49","slug":"bureau-de-lambassade-du-kazakhstan-a-bonn-en-allemagne","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/bureau-de-lambassade-du-kazakhstan-a-bonn-en-allemagne\/","title":{"rendered":"Bureau de l&rsquo;ambassade du Kazakhstan \u00e0 Bonn, en Allemagne"},"content":{"rendered":"<div id=\"trave-26857947\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Coordonn\u00e9es de la succursale de l&rsquo;ambassade du Kazakhstan \u00e0 Bonn, en Allemagne<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\n53225 Bonn<br \/>\nAllemagne<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> Gaukhar Beiseyeva, repr\u00e9sentant<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+49) 228 40 38 720<br \/>\n<strong>Fax:<\/strong> (+49) 228 40 38 720<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> 09h00-13h00 (ferm\u00e9 mercredi mercredi)<\/p>\n<div id=\"trave-1801037022\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Coordonn\u00e9es de la succursale de l&rsquo;ambassade du Kazakhstan \u00e0 Bonn, en Allemagne Adresse: 53225 Bonn Allemagne Ambassadeur: Gaukhar Beiseyeva, repr\u00e9sentant T\u00e9l\u00e9phone: (+49) 228 40 38 720 Fax: (+49) 228 40 38 720 Email: Site Internet: Heures de travail: 09h00-13h00 (ferm\u00e9 mercredi mercredi)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10820,11989,11978,5747],"tags":[11615],"class_list":["post-86893","post","type-post","status-publish","format-standard","hentry","category-allemagne","category-branches-de-lambassade-du-kazakhstan","category-bureaux-dambassade-en-allemagne","category-kazakhstan","tag-direction-de-lambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/86893"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=86893"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/86893\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=86893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=86893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=86893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}