{"id":86770,"date":"2019-08-27T07:45:06","date_gmt":"2019-08-27T07:45:06","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-du-laos-a-berlin-allemagne\/"},"modified":"2019-08-27T07:45:06","modified_gmt":"2019-08-27T07:45:06","slug":"ambassade-du-laos-a-berlin-allemagne","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-du-laos-a-berlin-allemagne\/","title":{"rendered":"Ambassade du Laos \u00e0 Berlin, Allemagne"},"content":{"rendered":"<div id=\"trave-2562979049\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails de l&rsquo;ambassade laotienne \u00e0 Berlin, en Allemagne<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\n14193 Berlin<br \/>\nAllemagne<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> M. Sithong Chitnhothinh, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+49) 30 89 06 06 48<br \/>\n<strong>Fax:<\/strong> (+49) 30 89 06 06 48<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-2245765372\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails de l&rsquo;ambassade laotienne \u00e0 Berlin, en Allemagne Adresse: 14193 Berlin Allemagne Ambassadeur: M. Sithong Chitnhothinh, ambassadeur T\u00e9l\u00e9phone: (+49) 30 89 06 06 48 Fax: (+49) 30 89 06 06 48 Email: Site Internet: Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10820,11315,11975,5817],"tags":[10806],"class_list":["post-86770","post","type-post","status-publish","format-standard","hentry","category-allemagne","category-ambassades-du-laos","category-ambassades-en-allemagne","category-laos","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/86770"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=86770"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/86770\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=86770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=86770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=86770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}