{"id":86088,"date":"2019-08-27T07:33:34","date_gmt":"2019-08-27T07:33:34","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-norvege-a-paris-france\/"},"modified":"2019-08-27T07:33:34","modified_gmt":"2019-08-27T07:33:34","slug":"ambassade-de-norvege-a-paris-france","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-norvege-a-paris-france\/","title":{"rendered":"Ambassade de Norv\u00e8ge \u00e0 Paris, France"},"content":{"rendered":"<div id=\"trave-2774879418\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Ambassade de Norv\u00e8ge \u00e0 Paris, France<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\n28, rue Bayard, 5\u00e8me \u00e9tage<br \/>\n75008 Paris<br \/>\nFrance<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> M. Rolf Einar Fife, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+33) 1 53.67.04.00<br \/>\n<strong>Fax:<\/strong> (+33) 1 53.67.04.40<br \/>\n<strong>Email:<\/strong> emb.paris@mfa.no<br \/>\nkonsulat.paris@mfa.no<br \/>\n<strong>Site Internet:<\/strong> www.norway.no\/fr\/france<\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-277379224\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ambassade de Norv\u00e8ge \u00e0 Paris, France Adresse: 28, rue Bayard, 5\u00e8me \u00e9tage 75008 Paris France Ambassadeur: M. Rolf Einar Fife, ambassadeur T\u00e9l\u00e9phone: (+33) 1 53.67.04.00 Fax: (+33) 1 53.67.04.40 Email: emb.paris@mfa.no konsulat.paris@mfa.no Site Internet: www.norway.no\/fr\/france Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10882,11940,5418,10881],"tags":[10806],"class_list":["post-86088","post","type-post","status-publish","format-standard","hentry","category-ambassades-de-norvege","category-ambassades-en-france","category-france","category-norvege","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/86088"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=86088"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/86088\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=86088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=86088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=86088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}