{"id":83603,"date":"2019-08-27T06:53:03","date_gmt":"2019-08-27T06:53:03","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-la-republique-de-coree-a-san-jose-costa-rica\/"},"modified":"2019-08-27T06:53:03","modified_gmt":"2019-08-27T06:53:03","slug":"ambassade-de-la-republique-de-coree-a-san-jose-costa-rica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-la-republique-de-coree-a-san-jose-costa-rica\/","title":{"rendered":"Ambassade de la R\u00e9publique de Cor\u00e9e \u00e0 San Jos\u00e9, Costa Rica"},"content":{"rendered":"<div id=\"trave-504934556\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Ambassade de Cor\u00e9e du Sud \u00e0 San Jos\u00e9, Costa Rica<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nRestaurante del Rostipollos Trejos Montealegre en<br \/>\nSan Rafael de Escaz\u00c3\u00ba<br \/>\nApartado postal 838<br \/>\n1007 Paseo Col\u00f3n, San Jos\u00e9 \u00a9<br \/>\nCosta Rica<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong><br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+506) 2588-0852<br \/>\n<strong>Fax:<\/strong> (+506) 2588-0760<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> cri.mofa.go.kr<\/p>\n<p><strong>Heures de travail:<\/strong> 08h00-17h00<\/p>\n<div id=\"trave-629471509\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ambassade de Cor\u00e9e du Sud \u00e0 San Jos\u00e9, Costa Rica Adresse: Restaurante del Rostipollos Trejos Montealegre en San Rafael de Escaz\u00c3\u00ba Apartado postal 838 1007 Paseo Col\u00f3n, San Jos\u00e9 \u00a9 Costa Rica Ambassadeur: T\u00e9l\u00e9phone: (+506) 2588-0852 Fax: (+506) 2588-0760 Email: Site Internet: cri.mofa.go.kr Heures de travail: 08h00-17h00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11801,10880,10879,5199],"tags":[10806],"class_list":["post-83603","post","type-post","status-publish","format-standard","hentry","category-ambassades-au-costa-rica","category-ambassades-de-coree-du-sud","category-coree-du-sud","category-costa-rica","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/83603"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=83603"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/83603\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=83603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=83603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=83603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}