{"id":82563,"date":"2019-08-27T06:36:34","date_gmt":"2019-08-27T06:36:34","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-du-cameroun-a-ndjamena-tchad\/"},"modified":"2019-08-27T06:36:34","modified_gmt":"2019-08-27T06:36:34","slug":"ambassade-du-cameroun-a-ndjamena-tchad","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-du-cameroun-a-ndjamena-tchad\/","title":{"rendered":"Ambassade du Cameroun \u00e0 N&rsquo;Djamena, Tchad"},"content":{"rendered":"<div id=\"trave-3768195155\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails d&rsquo;ambassade du Cameroun \u00e0 N&rsquo;Djamena, au Tchad<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nRue des Poids Lourds<br \/>\nQuartier Kl\u00e9mat<br \/>\nB.P.58<br \/>\nN&rsquo;Djamena<br \/>\nTchad<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> M. Mohaman Sani Tanimou, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+235) 22-52-34-73<br \/>\n(+235) 22-52-28-94<br \/>\n<strong>Fax:<\/strong> (+235) 22-52-68-00<br \/>\n<strong>Email:<\/strong> ambacamtchad@yahoo.com<br \/>\nnjilarene@yahoo.fr<br \/>\nnambacam@intnet.td<br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-3750448153\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails d&rsquo;ambassade du Cameroun \u00e0 N&rsquo;Djamena, au Tchad Adresse: Rue des Poids Lourds Quartier Kl\u00e9mat B.P.58 N&rsquo;Djamena Tchad Ambassadeur: M. Mohaman Sani Tanimou, ambassadeur T\u00e9l\u00e9phone: (+235) 22-52-34-73 (+235) 22-52-28-94 Fax: (+235) 22-52-68-00 Email: ambacamtchad@yahoo.com njilarene@yahoo.fr nambacam@intnet.td Site Internet: Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11736,11064,11063,10996],"tags":[10806],"class_list":["post-82563","post","type-post","status-publish","format-standard","hentry","category-ambassades-au-tchad","category-ambassades-du-cameroun","category-cameroun","category-tchad","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/82563"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=82563"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/82563\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=82563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=82563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=82563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}