{"id":82536,"date":"2019-08-27T06:35:46","date_gmt":"2019-08-27T06:35:46","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-du-soudan-a-bangui-republique-centrafricaine\/"},"modified":"2019-08-27T06:35:46","modified_gmt":"2019-08-27T06:35:46","slug":"ambassade-du-soudan-a-bangui-republique-centrafricaine","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-du-soudan-a-bangui-republique-centrafricaine\/","title":{"rendered":"Ambassade du Soudan \u00e0 Bangui, R\u00e9publique centrafricaine"},"content":{"rendered":"<div id=\"trave-292916324\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails d&rsquo;ambassade du Soudan \u00e0 Bangui, R\u00e9publique centrafricaine<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nAvenue de France<br \/>\nBP 1351<br \/>\nBangui<br \/>\nR\u00e9publique centrafricaine<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong><br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+236) 2161-3821<br \/>\n<strong>Fax:<\/strong> (+236) 2161-7959<br \/>\n<strong>Email:<\/strong> sudanibangui@gmail.com<br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-2709343399\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails d&rsquo;ambassade du Soudan \u00e0 Bangui, R\u00e9publique centrafricaine Adresse: Avenue de France BP 1351 Bangui R\u00e9publique centrafricaine Ambassadeur: T\u00e9l\u00e9phone: (+236) 2161-3821 Fax: (+236) 2161-7959 Email: sudanibangui@gmail.com Site Internet: Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10999,11733,11496,10998],"tags":[10806],"class_list":["post-82536","post","type-post","status-publish","format-standard","hentry","category-ambassades-du-soudan","category-ambassades-en-republique-centrafricaine","category-republique-centrafricaine","category-soudan","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/82536"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=82536"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/82536\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=82536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=82536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=82536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}