{"id":82069,"date":"2019-08-27T06:28:41","date_gmt":"2019-08-27T06:28:41","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-des-pays-bas-a-ottawa-canada\/"},"modified":"2019-08-27T06:28:41","modified_gmt":"2019-08-27T06:28:41","slug":"ambassade-des-pays-bas-a-ottawa-canada","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-des-pays-bas-a-ottawa-canada\/","title":{"rendered":"Ambassade des Pays-Bas \u00e0 Ottawa, Canada"},"content":{"rendered":"<div id=\"trave-2446701188\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails de l&rsquo;ambassade des Pays-Bas \u00e0 Ottawa, Canada<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nOttawa, ON K1R 1A4<br \/>\nCanada<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> Henk van der Zwan, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+1) 613 237 6471<br \/>\n<strong>Fax:<\/strong> (+1) 613 237 6471<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> 08h30-16h30, ferm\u00e9 le mercredi<\/p>\n<div id=\"trave-3453587915\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails de l&rsquo;ambassade des Pays-Bas \u00e0 Ottawa, Canada Adresse: Ottawa, ON K1R 1A4 Canada Ambassadeur: Henk van der Zwan, ambassadeur T\u00e9l\u00e9phone: (+1) 613 237 6471 Fax: (+1) 613 237 6471 Email: Site Internet: Heures de travail: 08h30-16h30, ferm\u00e9 le mercredi<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11695,10848,5085,10847],"tags":[10806],"class_list":["post-82069","post","type-post","status-publish","format-standard","hentry","category-ambassades-au-canada","category-ambassades-des-pays-bas","category-canada","category-pays-bas","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/82069"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=82069"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/82069\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=82069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=82069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=82069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}