{"id":80987,"date":"2019-08-27T06:11:46","date_gmt":"2019-08-27T06:11:46","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-nouvelle-zelande-a-brasilia-bresil\/"},"modified":"2019-08-27T06:11:46","modified_gmt":"2019-08-27T06:11:46","slug":"ambassade-de-nouvelle-zelande-a-brasilia-bresil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-nouvelle-zelande-a-brasilia-bresil\/","title":{"rendered":"Ambassade de Nouvelle-Z\u00e9lande \u00e0 Brasilia, Br\u00e9sil"},"content":{"rendered":"<div id=\"trave-2507924378\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails de l&rsquo;ambassade de Nouvelle-Z\u00e9lande \u00e0 Brasilia, au Br\u00e9sil<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nLago Sul<br \/>\n71625-160 Brasilia DF<br \/>\nBr\u00e9sil<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> Caroline Peta Bilkey, ambassadrice<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+55) 61 3248 9916<br \/>\n(+55) 11 3248 9900<br \/>\n<strong>Fax:<\/strong> (+55) 61 3248 9916<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> 08h30-17h00<\/p>\n<div id=\"trave-3125727418\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails de l&rsquo;ambassade de Nouvelle-Z\u00e9lande \u00e0 Brasilia, au Br\u00e9sil Adresse: Lago Sul 71625-160 Brasilia DF Br\u00e9sil Ambassadeur: Caroline Peta Bilkey, ambassadrice T\u00e9l\u00e9phone: (+55) 61 3248 9916 (+55) 11 3248 9900 Fax: (+55) 61 3248 9916 Email: Site Internet: Heures de travail: 08h30-17h00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11626,11182,10855,11181],"tags":[10806],"class_list":["post-80987","post","type-post","status-publish","format-standard","hentry","category-ambassades-au-bresil","category-ambassades-de-nouvelle-zelande","category-bresil","category-nouvelle-zelande","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/80987"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=80987"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/80987\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=80987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=80987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=80987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}