{"id":80256,"date":"2019-08-27T05:56:55","date_gmt":"2019-08-27T05:56:55","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-slovenie-a-bruxelles-belgique\/"},"modified":"2019-08-27T05:56:55","modified_gmt":"2019-08-27T05:56:55","slug":"ambassade-de-slovenie-a-bruxelles-belgique","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-slovenie-a-bruxelles-belgique\/","title":{"rendered":"Ambassade de Slov\u00e9nie \u00e0 Bruxelles, Belgique"},"content":{"rendered":"<div id=\"trave-4160564212\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails de l&rsquo;ambassade de Slov\u00e9nie \u00e0 Bruxelles, Belgique<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nRue du commerce 44, 4\u00e8me \u00e9tage<br \/>\n1000 Bruxelles<br \/>\nBelgique<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> Dr Rado Genorio, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+32) 2 213 6337<br \/>\n<strong>Fax:<\/strong> (+32) 2 213 6429<br \/>\n<strong>Email:<\/strong> sloembassy.brussels@gov.si<br \/>\n<strong>Site Internet:<\/strong> www.bruselj.veleposlanistvo.si<\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-1668656505\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails de l&rsquo;ambassade de Slov\u00e9nie \u00e0 Bruxelles, Belgique Adresse: Rue du commerce 44, 4\u00e8me \u00e9tage 1000 Bruxelles Belgique Ambassadeur: Dr Rado Genorio, ambassadeur T\u00e9l\u00e9phone: (+32) 2 213 6337 Fax: (+32) 2 213 6429 Email: sloembassy.brussels@gov.si Site Internet: www.bruselj.veleposlanistvo.si Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10913,11498,10867,10912],"tags":[10806],"class_list":["post-80256","post","type-post","status-publish","format-standard","hentry","category-ambassades-de-slovenie","category-ambassades-en-belgique","category-belgique","category-la-slovenie","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/80256"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=80256"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/80256\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=80256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=80256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=80256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}