{"id":78753,"date":"2019-08-27T05:31:26","date_gmt":"2019-08-27T05:31:26","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-du-panama-a-buenos-aires-argentine\/"},"modified":"2019-08-27T05:31:26","modified_gmt":"2019-08-27T05:31:26","slug":"ambassade-du-panama-a-buenos-aires-argentine","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-du-panama-a-buenos-aires-argentine\/","title":{"rendered":"Ambassade du Panama \u00e0 Buenos Aires, Argentine"},"content":{"rendered":"<div id=\"trave-2407550600\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Ambassade du Panama \u00e0 Buenos Aires, Argentine<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\n1060 Buenos Aires<br \/>\nArgentine<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> Dionisio de Gracia Guill\u00e9n, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+54) 11 4315 5855<br \/>\n<strong>Fax:<\/strong> (+54) 11 4315 5855<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> Lundi-jeudi: 11h00-14h00<\/p>\n<div id=\"trave-3814066416\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ambassade du Panama \u00e0 Buenos Aires, Argentine Adresse: 1060 Buenos Aires Argentine Ambassadeur: Dionisio de Gracia Guill\u00e9n, ambassadeur T\u00e9l\u00e9phone: (+54) 11 4315 5855 Fax: (+54) 11 4315 5855 Email: Site Internet: Heures de travail: Lundi-jeudi: 11h00-14h00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11208,11155,11030,6231],"tags":[10806],"class_list":["post-78753","post","type-post","status-publish","format-standard","hentry","category-ambassades-du-panama","category-ambassades-en-argentine","category-argentine","category-panama","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/78753"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=78753"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/78753\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=78753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=78753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=78753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}