{"id":78402,"date":"2019-08-27T05:26:01","date_gmt":"2019-08-27T05:26:01","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-guinee-equatoriale-a-luanda-angola\/"},"modified":"2019-08-27T05:26:01","modified_gmt":"2019-08-27T05:26:01","slug":"ambassade-de-guinee-equatoriale-a-luanda-angola","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-guinee-equatoriale-a-luanda-angola\/","title":{"rendered":"Ambassade de Guin\u00e9e \u00e9quatoriale \u00e0 Luanda, Angola"},"content":{"rendered":"<div id=\"trave-4026462498\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Ambassade de Guin\u00e9e \u00e9quatoriale \u00e0 Luanda, Angola<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nRua Kateculo Mengo 107\/109<br \/>\nC. P. 508<br \/>\nLuanda<br \/>\nAngola<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> Marcos Mba Ondo, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+244) 222 353 939<br \/>\n(+244) 222 325 936<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> embajsecretaria@gmail.com<br \/>\nembguineequatorial@hotmail.com<br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-2343256418\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ambassade de Guin\u00e9e \u00e9quatoriale \u00e0 Luanda, Angola Adresse: Rua Kateculo Mengo 107\/109 C. P. 508 Luanda Angola Ambassadeur: Marcos Mba Ondo, ambassadeur T\u00e9l\u00e9phone: (+244) 222 353 939 (+244) 222 325 936 Fax: Email: embajsecretaria@gmail.com embguineequatorial@hotmail.com Site Internet: Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11097,11113,4793,11112],"tags":[10806],"class_list":["post-78402","post","type-post","status-publish","format-standard","hentry","category-ambassades-en-angola","category-ambassades-guineennes-equatoriales","category-angola","category-guinee-equatoriale","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/78402"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=78402"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/78402\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=78402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=78402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=78402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}