{"id":78307,"date":"2019-08-27T05:23:58","date_gmt":"2019-08-27T05:23:58","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-la-republique-democratique-arabe-sahraouie-a-alger-algerie\/"},"modified":"2019-08-27T05:23:58","modified_gmt":"2019-08-27T05:23:58","slug":"ambassade-de-la-republique-democratique-arabe-sahraouie-a-alger-algerie","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-la-republique-democratique-arabe-sahraouie-a-alger-algerie\/","title":{"rendered":"Ambassade de la R\u00e9publique d\u00e9mocratique arabe sahraouie \u00e0 Alger, Alg\u00e9rie"},"content":{"rendered":"<div id=\"trave-3244775376\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>D\u00e9tails de l&rsquo;ambassade sahraouie \u00e0 Alger, Alg\u00e9rie<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\n1, Rue Franklin Roosevelt<br \/>\n16000 Alger<br \/>\nAlg\u00e9rie<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> Abdelkader Talib Omar, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+213) 21.74.79.32<br \/>\n<strong>Fax:<\/strong> (+213) 21.74.72.06<br \/>\n<strong>Email:<\/strong> contact@amb-rasd.org<br \/>\ninfo@amb-rasd.org<br \/>\n<strong>Site Internet:<\/strong> amb-rasd.org<\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-1609903202\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9tails de l&rsquo;ambassade sahraouie \u00e0 Alger, Alg\u00e9rie Adresse: 1, Rue Franklin Roosevelt 16000 Alger Alg\u00e9rie Ambassadeur: Abdelkader Talib Omar, ambassadeur T\u00e9l\u00e9phone: (+213) 21.74.79.32 Fax: (+213) 21.74.72.06 Email: contact@amb-rasd.org info@amb-rasd.org Site Internet: amb-rasd.org Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10972,10995,11061,11060],"tags":[10806],"class_list":["post-78307","post","type-post","status-publish","format-standard","hentry","category-algerie","category-ambassades-en-algerie","category-ambassades-sahraouies","category-republique-arabe-sahraouie-democratique","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/78307"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=78307"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/78307\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=78307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=78307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=78307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}