{"id":104264,"date":"2019-08-29T16:46:53","date_gmt":"2019-08-29T16:46:53","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-cuba-a-sanaa-yemen\/"},"modified":"2019-08-29T16:46:53","modified_gmt":"2019-08-29T16:46:53","slug":"ambassade-de-cuba-a-sanaa-yemen","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-cuba-a-sanaa-yemen\/","title":{"rendered":"Ambassade de Cuba \u00e0 Sanaa, Y\u00e9men"},"content":{"rendered":"<div id=\"trave-1636219326\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Ambassade de Cuba \u00e0 Sanaa, Y\u00e9men<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nB\u00e2timent 9 fin de la6e rue B<br \/>\npr\u00e8s deAmman Street, Zone SAFA<br \/>\nP.O.Box 15256<br \/>\nSanaa \u20ac \u2122 s<br \/>\nY\u00e9men<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> M. Buenaventura Reyes Acosta, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+967) 1 44 2321<br \/>\n(+967) 1 44 6557<br \/>\n<strong>Fax:<\/strong> (+967) 1 44 2322<br \/>\n<strong>Email:<\/strong> embacubayem@y.net.ye<br \/>\nembacubayemen@y.net.ye<br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> <\/p>\n<div id=\"trave-530685543\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ambassade de Cuba \u00e0 Sanaa, Y\u00e9men Adresse: B\u00e2timent 9 fin de la6e rue B pr\u00e8s deAmman Street, Zone SAFA P.O.Box 15256 Sanaa \u20ac \u2122 s Y\u00e9men Ambassadeur: M. Buenaventura Reyes Acosta, ambassadeur T\u00e9l\u00e9phone: (+967) 1 44 2321 (+967) 1 44 6557 Fax: (+967) 1 44 2322 Email: embacubayem@y.net.ye embacubayemen@y.net.ye Site Internet: Heures de travail:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13223,11001,5228,6889],"tags":[10806],"class_list":["post-104264","post","type-post","status-publish","format-standard","hentry","category-ambassades-au-yemen","category-ambassades-de-cuba","category-cuba","category-yemen","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/104264"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=104264"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/104264\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=104264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=104264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=104264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}