{"id":104109,"date":"2019-08-29T16:42:59","date_gmt":"2019-08-29T16:42:59","guid":{"rendered":"https:\/\/travelqa.com\/ambassade-de-saint-vincent-et-les-grenadines-a-caracas-venezuela\/"},"modified":"2019-08-29T16:42:59","modified_gmt":"2019-08-29T16:42:59","slug":"ambassade-de-saint-vincent-et-les-grenadines-a-caracas-venezuela","status":"publish","type":"post","link":"https:\/\/travelqa.com\/fr\/ambassade-de-saint-vincent-et-les-grenadines-a-caracas-venezuela\/","title":{"rendered":"Ambassade de Saint-Vincent-et-les Grenadines \u00e0 Caracas, Venezuela"},"content":{"rendered":"<div id=\"trave-3152514283\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Ambassade de Saint-Vincent-et-Grenadine \u00e0 Caracas, Venezuela<\/h3>\n<p><strong><br \/>\nAdresse:<\/strong><br \/>\nUrbanisation Altamira<br \/>\n1060 Caracas<br \/>\nVenezuela<br \/>\n<strong><br \/>\nAmbassadeur:<\/strong> M. Andreas Wickham, ambassadeur<br \/>\n<strong>T\u00e9l\u00e9phone:<\/strong> (+58) 212 263 0857<br \/>\n<strong>Fax:<\/strong> (+58) 212 263 0857<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Site Internet:<\/strong> <\/p>\n<p><strong>Heures de travail:<\/strong> 09h00-16h00<\/p>\n<div id=\"trave-3835567031\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ambassade de Saint-Vincent-et-Grenadine \u00e0 Caracas, Venezuela Adresse: Urbanisation Altamira 1060 Caracas Venezuela Ambassadeur: M. Andreas Wickham, ambassadeur T\u00e9l\u00e9phone: (+58) 212 263 0857 Fax: (+58) 212 263 0857 Email: Site Internet: Heures de travail: 09h00-16h00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12872,11544,11436,6866],"tags":[10806],"class_list":["post-104109","post","type-post","status-publish","format-standard","hentry","category-ambassades-au-venezuela","category-ambassades-de-saint-vincent-et-grenadine","category-saint-vincent-et-les-grenadines","category-venezuela","tag-ambassade"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/104109"}],"collection":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/comments?post=104109"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/posts\/104109\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/media?parent=104109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/categories?post=104109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/fr\/wp-json\/wp\/v2\/tags?post=104109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}