{"id":135261,"date":"2019-09-01T10:29:48","date_gmt":"2019-09-01T10:29:48","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-alemania-en-lusaka-zambia\/"},"modified":"2019-09-01T10:29:48","modified_gmt":"2019-09-01T10:29:48","slug":"embajada-de-alemania-en-lusaka-zambia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-alemania-en-lusaka-zambia\/","title":{"rendered":"Embajada de Alemania en Lusaka, Zambia"},"content":{"rendered":"<div id=\"trave-2830921334\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la embajada alemana en Lusaka, Zambia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n5219 Haile Selassie Avenue<br \/>\nLongacres<br \/>\nLusaka<br \/>\nZambia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Achim Burkart, embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+260) 211 25 06 44<br \/>\n(+260) 211 25 12 62<br \/>\n<strong>Fax:<\/strong> (+260) 211 25 40 14<br \/>\n<strong>Email:<\/strong> info@lusaka.diplo.de<br \/>\n<strong>Sitio web:<\/strong> www.lusaka.diplo.de<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2532540493\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la embajada alemana en Lusaka, Zambia Direcci\u00f3n: 5219 Haile Selassie Avenue Longacres Lusaka Zambia Embajador: Achim Burkart, embajador Tel\u00e9fono: (+260) 211 25 06 44 (+260) 211 25 12 62 Fax: (+260) 211 25 40 14 Email: info@lusaka.diplo.de Sitio web: www.lusaka.diplo.de Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,12991,15257,6896],"tags":[12975],"class_list":["post-135261","post","type-post","status-publish","format-standard","hentry","category-alemania","category-embajadas-alemanas","category-embajadas-en-zambia","category-zambia","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/135261"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=135261"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/135261\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=135261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=135261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=135261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}