{"id":135204,"date":"2019-09-01T10:28:57","date_gmt":"2019-09-01T10:28:57","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-cuba-en-sana-yemen\/"},"modified":"2019-09-01T10:28:57","modified_gmt":"2019-09-01T10:28:57","slug":"embajada-de-cuba-en-sana-yemen","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-cuba-en-sana-yemen\/","title":{"rendered":"Embajada de Cuba en San\u00e1, Yemen"},"content":{"rendered":"<div id=\"trave-3107741361\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Cuba en San\u00e1, Yemen<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nLa construcci\u00f3n de 9 final de la calle 6 B<br \/>\ncerca de Amman Street, Zona SAFA<br \/>\nP.O.Box 15256<br \/>\n\u2122 \u20ac s Sanaa<br \/>\nYemen<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Buenaventura Reyes Acosta, Embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+967) 1 44 2321<br \/>\n(+967) 1 44 6557<br \/>\n<strong>Fax:<\/strong> (+967) 1 44 2322<br \/>\n<strong>Email:<\/strong> embacubayem@y.net.ye<br \/>\nembacubayemen@y.net.ye<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-846820118\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Cuba en San\u00e1, Yemen Direcci\u00f3n: La construcci\u00f3n de 9 final de la calle 6 B cerca de Amman Street, Zona SAFA P.O.Box 15256 \u2122 \u20ac s Sanaa Yemen Embajador: Sr. Buenaventura Reyes Acosta, Embajador Tel\u00e9fono: (+967) 1 44 2321 (+967) 1 44 6557 Fax: (+967) 1 44 2322 Email: embacubayem@y.net.ye [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5228,13327,15254,6889],"tags":[12975],"class_list":["post-135204","post","type-post","status-publish","format-standard","hentry","category-cuba","category-embajadas-cubanas","category-embajadas-en-yemen","category-yemen","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/135204"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=135204"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/135204\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=135204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=135204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=135204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}