{"id":134933,"date":"2019-09-01T10:25:33","date_gmt":"2019-09-01T10:25:33","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-eslovaquia-en-caracas-venezuela\/"},"modified":"2019-09-01T10:25:33","modified_gmt":"2019-09-01T10:25:33","slug":"consulado-de-eslovaquia-en-caracas-venezuela","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-eslovaquia-en-caracas-venezuela\/","title":{"rendered":"Consulado de Eslovaquia en Caracas, Venezuela"},"content":{"rendered":"<div id=\"trave-1226183988\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado eslovaco en Caracas, Venezuela<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nAvenida Francisco de Miranda Edificio Cavendes 12 \u00b0 piso<br \/>\nLos Palos Grandes apartado 68 606<br \/>\nCaracas 1062<br \/>\nVenezuela<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Manuel Antonio Polanco Fernandez, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+58) 212 283 9444<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-4071940239\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado eslovaco en Caracas, Venezuela Direcci\u00f3n: Avenida Francisco de Miranda Edificio Cavendes 12 \u00b0 piso Los Palos Grandes apartado 68 606 Caracas 1062 Venezuela Embajador: Mr Manuel Antonio Polanco Fernandez, C\u00f3nsul Honorario Tel\u00e9fono: (+58) 212 283 9444 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15241,13675,13236,6866],"tags":[12978],"class_list":["post-134933","post","type-post","status-publish","format-standard","hentry","category-consulados-en-venezuela","category-consulados-eslovacos","category-eslovaquia","category-venezuela","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134933"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134933"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134933\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}