{"id":134913,"date":"2019-09-01T10:25:20","date_gmt":"2019-09-01T10:25:20","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-lituania-en-maracaibo-venezuela\/"},"modified":"2019-09-01T10:25:20","modified_gmt":"2019-09-01T10:25:20","slug":"consulado-de-lituania-en-maracaibo-venezuela","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-lituania-en-maracaibo-venezuela\/","title":{"rendered":"Consulado de Lituania en Maracaibo, Venezuela"},"content":{"rendered":"<div id=\"trave-3790208392\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Lituania en Maracaibo, Venezuela<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nc \/ o Grupo Empresarial Fimap CA<br \/>\nAv.Principal de San Francisco<br \/>\nDetras del Venecemos Mara San Francisco<br \/>\n4004 Estados Unidos Zulia<br \/>\nMaracaibo<br \/>\nVenezuela<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Boris Petrasevicius, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+58) 261 761 3567<br \/>\n<strong>Fax:<\/strong> (+58) 261 761 3567<br \/>\n<strong>Email:<\/strong> boris41@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3094114582\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Lituania en Maracaibo, Venezuela Direcci\u00f3n: c \/ o Grupo Empresarial Fimap CA Av.Principal de San Francisco Detras del Venecemos Mara San Francisco 4004 Estados Unidos Zulia Maracaibo Venezuela Embajador: Mr Boris Petrasevicius, C\u00f3nsul Honorario Tel\u00e9fono: (+58) 261 761 3567 Fax: (+58) 261 761 3567 Email: boris41@gmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13608,15241,13184,6866],"tags":[12978],"class_list":["post-134913","post","type-post","status-publish","format-standard","hentry","category-consulados-de-lituania","category-consulados-en-venezuela","category-lituania","category-venezuela","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134913"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134913"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134913\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}