{"id":134793,"date":"2019-09-01T10:22:42","date_gmt":"2019-09-01T10:22:42","guid":{"rendered":"https:\/\/travelqa.com\/nunciatura-apostolica-de-la-santa-sede-en-montevideo-uruguay\/"},"modified":"2019-09-01T10:22:42","modified_gmt":"2019-09-01T10:22:42","slug":"nunciatura-apostolica-de-la-santa-sede-en-montevideo-uruguay","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/nunciatura-apostolica-de-la-santa-sede-en-montevideo-uruguay\/","title":{"rendered":"Nunciatura Apost\u00f3lica de la Santa Sede en Montevideo, Uruguay"},"content":{"rendered":"<div id=\"trave-2214318459\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Nunciatura Apost\u00f3lica de la Santa Sede en Montevideo, Uruguay<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCP 1503<br \/>\n11.300 Montevideo<br \/>\nUruguay<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Arzobispo George Panikulam, Nuncio Apost\u00f3lico<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+598) 2 707.22.09<br \/>\n<strong>Fax:<\/strong> (+598) 2 707.22.09<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 13.00 y 15.30 a 17.00<\/p>\n<div id=\"trave-2888667669\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Nunciatura Apost\u00f3lica de la Santa Sede en Montevideo, Uruguay Direcci\u00f3n: CP 1503 11.300 Montevideo Uruguay Embajador: Arzobispo George Panikulam, Nuncio Apost\u00f3lico Tel\u00e9fono: (+598) 2 707.22.09 Fax: (+598) 2 707.22.09 Email: Sitio web: Horas de oficina: 09.00 a 13.00 y 15.30 a 17.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15230,13258,13260,6840],"tags":[13262],"class_list":["post-134793","post","type-post","status-publish","format-standard","hentry","category-nunciatura-apostolica-en-uruguay","category-santa-sede","category-santa-sede-nunciatura-apostolica","category-uruguay","tag-nunciatura-apostolica"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134793"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134793"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134793\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}