{"id":134762,"date":"2019-09-01T10:22:24","date_gmt":"2019-09-01T10:22:24","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-noruega-en-montevideo-uruguay\/"},"modified":"2019-09-01T10:22:24","modified_gmt":"2019-09-01T10:22:24","slug":"consulado-general-de-noruega-en-montevideo-uruguay","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-noruega-en-montevideo-uruguay\/","title":{"rendered":"Consulado General de Noruega en Montevideo, Uruguay"},"content":{"rendered":"<div id=\"trave-2084690795\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Noruega en Montevideo, Uruguay<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n11000 Montevideo<br \/>\nUruguay<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+598) 2 916-3935<br \/>\n<strong>Fax:<\/strong> (+598) 2 916-3856<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 14.00-17.00<\/p>\n<div id=\"trave-1378598803\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Noruega en Montevideo, Uruguay Direcci\u00f3n: 11000 Montevideo Uruguay Embajador: Tel\u00e9fono: (+598) 2 916-3935 Fax: (+598) 2 916-3856 Email: Sitio web: Horas de oficina: 14.00-17.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13261,15225,13153,6840],"tags":[12988],"class_list":["post-134762","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-noruega","category-consulado-general-en-uruguay","category-noruega","category-uruguay","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134762"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134762"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134762\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}