{"id":134662,"date":"2019-09-01T10:21:02","date_gmt":"2019-09-01T10:21:02","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-honduras-en-nueva-orleans-estados-unidos\/"},"modified":"2019-09-01T10:21:02","modified_gmt":"2019-09-01T10:21:02","slug":"consulado-general-de-honduras-en-nueva-orleans-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-honduras-en-nueva-orleans-estados-unidos\/","title":{"rendered":"Consulado General de Honduras en Nueva Orleans, Estados Unidos"},"content":{"rendered":"<div id=\"trave-1638332473\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado hondure\u00f1o en Nueva Orleans, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n365 Canal Street, Suite 400<br \/>\nNew Orleans, LA 70130<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Roberto Mart\u00ednez Castellanos, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) 504-523-0544<br \/>\n(+1) 504-535-5933<br \/>\n<strong>Fax:<\/strong> (+1) 504-523-0544<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1201807031\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado hondure\u00f1o en Nueva Orleans, Estados Unidos Direcci\u00f3n: 365 Canal Street, Suite 400 New Orleans, LA 70130 Estados Unidos Embajador: Roberto Mart\u00ednez Castellanos, C\u00f3nsul General Tel\u00e9fono: (+1) 504-523-0544 (+1) 504-535-5933 Fax: (+1) 504-523-0544 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14021,15206,13059,5584],"tags":[12988],"class_list":["post-134662","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-honduras","category-consulado-general-en-estados-unidos","category-estados-unidos","category-honduras","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134662"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134662"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134662\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}