{"id":134491,"date":"2019-09-01T10:19:10","date_gmt":"2019-09-01T10:19:10","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-tanzania-en-detroit-estados-unidos\/"},"modified":"2019-09-01T10:19:10","modified_gmt":"2019-09-01T10:19:10","slug":"consulado-de-tanzania-en-detroit-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-tanzania-en-detroit-estados-unidos\/","title":{"rendered":"Consulado de Tanzania en Detroit, Estados Unidos"},"content":{"rendered":"<div id=\"trave-1217770170\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Tanzania en Detroit, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nGrosse Points, MI 48236<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Robert Samuel Shumake, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) (313) 942-6576<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2849791321\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Tanzania en Detroit, Estados Unidos Direcci\u00f3n: Grosse Points, MI 48236 Estados Unidos Embajador: Robert Samuel Shumake, C\u00f3nsul Honorario Tel\u00e9fono: (+1) (313) 942-6576 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13489,15205,13059,6661],"tags":[12978],"class_list":["post-134491","post","type-post","status-publish","format-standard","hentry","category-consulados-de-tanzania","category-consulados-en-estados-unidos","category-estados-unidos","category-tanzania","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134491"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134491"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134491\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}