{"id":134435,"date":"2019-09-01T10:18:40","date_gmt":"2019-09-01T10:18:40","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-irlanda-en-atlanta-estados-unidos\/"},"modified":"2019-09-01T10:18:40","modified_gmt":"2019-09-01T10:18:40","slug":"consulado-general-de-irlanda-en-atlanta-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-irlanda-en-atlanta-estados-unidos\/","title":{"rendered":"Consulado General de Irlanda en Atlanta, Estados Unidos"},"content":{"rendered":"<div id=\"trave-891258614\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Irlanda en Atlanta, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nMonarch Plaza, Suite 260<br \/>\n3414 Peachtree Road, NE<br \/>\nAtlanta, GA 30326<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Adrian Farrell, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) 404-554-4980<br \/>\n<strong>Fax:<\/strong> (+1) 678-235-2201<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> www.dfa.ie\/irish-consulate\/atlanta\/<\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 12.00 y 13.00 a 16.00<\/p>\n<div id=\"trave-1367716661\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Irlanda en Atlanta, Estados Unidos Direcci\u00f3n: Monarch Plaza, Suite 260 3414 Peachtree Road, NE Atlanta, GA 30326 Estados Unidos Embajador: Adrian Farrell, C\u00f3nsul General Tel\u00e9fono: (+1) 404-554-4980 Fax: (+1) 678-235-2201 Email: Sitio web: www.dfa.ie\/irish-consulate\/atlanta\/ Horas de oficina: 09.00 a 12.00 y 13.00 a 16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15206,13692,13059,13582],"tags":[12988],"class_list":["post-134435","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-estados-unidos","category-consulado-general-irlandes","category-estados-unidos","category-irlanda","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134435"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134435"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134435\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}