{"id":134330,"date":"2019-09-01T10:17:29","date_gmt":"2019-09-01T10:17:29","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-guatemala-en-denver-estados-unidos\/"},"modified":"2019-09-01T10:17:29","modified_gmt":"2019-09-01T10:17:29","slug":"consulado-general-de-guatemala-en-denver-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-guatemala-en-denver-estados-unidos\/","title":{"rendered":"Consulado General de Guatemala en Denver, Estados Unidos"},"content":{"rendered":"<div id=\"trave-3545300109\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Guatemala en Denver, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n1001 S. Monaco Parkway, Suite 300<br \/>\nDenver, CO 80224<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Juan Fernando Valey Reyna, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) (303) 629-9210<br \/>\n<strong>Fax:<\/strong> (+1) (303) 629-9211<br \/>\n<strong>Email:<\/strong> consdenver@minex.gob.gt<br \/>\n<strong>Sitio web:<\/strong> www.consdenver.minex.gob.gt<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1865315878\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Guatemala en Denver, Estados Unidos Direcci\u00f3n: 1001 S. Monaco Parkway, Suite 300 Denver, CO 80224 Estados Unidos Embajador: Juan Fernando Valey Reyna, C\u00f3nsul General Tel\u00e9fono: (+1) (303) 629-9210 Fax: (+1) (303) 629-9211 Email: consdenver@minex.gob.gt Sitio web: www.consdenver.minex.gob.gt Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13938,15206,13059,5533],"tags":[12988],"class_list":["post-134330","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-guatemala","category-consulado-general-en-estados-unidos","category-estados-unidos","category-guatemala","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134330"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134330"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134330\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}