{"id":134140,"date":"2019-09-01T10:15:15","date_gmt":"2019-09-01T10:15:15","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-peru-en-san-francisco-estados-unidos\/"},"modified":"2019-09-01T10:15:15","modified_gmt":"2019-09-01T10:15:15","slug":"consulado-general-de-peru-en-san-francisco-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-peru-en-san-francisco-estados-unidos\/","title":{"rendered":"Consulado General de Per\u00fa en San Francisco, Estados Unidos"},"content":{"rendered":"<div id=\"trave-3398273959\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado peruano en San Francisco, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nSan Francisco, CA 94102<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Candy Gloria Ch\u00e1vez Gonzales, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) (415) 362 2836<br \/>\n<strong>Fax:<\/strong> (+1) (415) 362 2836<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3739281560\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado peruano en San Francisco, Estados Unidos Direcci\u00f3n: San Francisco, CA 94102 Estados Unidos Embajador: Candy Gloria Ch\u00e1vez Gonzales, C\u00f3nsul General Tel\u00e9fono: (+1) (415) 362 2836 Fax: (+1) (415) 362 2836 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15206,13595,13059,6261],"tags":[12988],"class_list":["post-134140","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-estados-unidos","category-consulado-general-peruano","category-estados-unidos","category-peru","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134140"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134140"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134140\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}