{"id":134105,"date":"2019-09-01T10:14:57","date_gmt":"2019-09-01T10:14:57","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-senegal-en-nueva-orleans-estados-unidos\/"},"modified":"2019-09-01T10:14:57","modified_gmt":"2019-09-01T10:14:57","slug":"consulado-de-senegal-en-nueva-orleans-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-senegal-en-nueva-orleans-estados-unidos\/","title":{"rendered":"Consulado de Senegal en Nueva Orleans, Estados Unidos"},"content":{"rendered":"<div id=\"trave-1978410313\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado senegal\u00e9s en Nueva Orleans, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n4529 Mohican Street<br \/>\nBaton Rouge, LA 70805<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Leonard A. Robinson, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) (225) 355-4174<br \/>\n<strong>Fax:<\/strong> (+1) (866) 354-0455<br \/>\n<strong>Email:<\/strong> ricusa2003@aol.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3016288742\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado senegal\u00e9s en Nueva Orleans, Estados Unidos Direcci\u00f3n: 4529 Mohican Street Baton Rouge, LA 70805 Estados Unidos Embajador: Mr Leonard A. Robinson, C\u00f3nsul Honorario Tel\u00e9fono: (+1) (225) 355-4174 Fax: (+1) (866) 354-0455 Email: ricusa2003@aol.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15205,13799,13059,6440],"tags":[12978],"class_list":["post-134105","post","type-post","status-publish","format-standard","hentry","category-consulados-en-estados-unidos","category-consulados-senegaleses","category-estados-unidos","category-senegal","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134105"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134105"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134105\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}