{"id":134102,"date":"2019-09-01T10:14:51","date_gmt":"2019-09-01T10:14:51","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-trinidad-y-tobago-en-miami-estados-unidos\/"},"modified":"2019-09-01T10:14:51","modified_gmt":"2019-09-01T10:14:51","slug":"consulado-general-de-trinidad-y-tobago-en-miami-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-trinidad-y-tobago-en-miami-estados-unidos\/","title":{"rendered":"Consulado General de Trinidad y Tobago en Miami, Estados Unidos"},"content":{"rendered":"<div id=\"trave-2655281195\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Trinidad y Tobago en Miami, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n1000 Brickell Avenue, Suite 800<br \/>\nMiami, FL 33131-3047<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Jenelle Pariag, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) 305-374-2199<br \/>\n<strong>Fax:<\/strong> (+1) 305-374-3199<br \/>\n<strong>Email:<\/strong> consulatemiami@foreign.gov.tt<br \/>\n<strong>Sitio web:<\/strong> foreign.gov.tt\/cgmiami<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1459620783\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Trinidad y Tobago en Miami, Estados Unidos Direcci\u00f3n: 1000 Brickell Avenue, Suite 800 Miami, FL 33131-3047 Estados Unidos Embajador: Jenelle Pariag, C\u00f3nsul General Tel\u00e9fono: (+1) 305-374-2199 Fax: (+1) 305-374-3199 Email: consulatemiami@foreign.gov.tt Sitio web: foreign.gov.tt\/cgmiami Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14082,15206,13059,13899],"tags":[12988],"class_list":["post-134102","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-trinidad-y-tobago","category-consulado-general-en-estados-unidos","category-estados-unidos","category-trinidad-y-tobago","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134102"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134102"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134102\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}