{"id":134075,"date":"2019-09-01T10:14:39","date_gmt":"2019-09-01T10:14:39","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-dinamarca-en-jacksonville-estados-unidos\/"},"modified":"2019-09-01T10:14:39","modified_gmt":"2019-09-01T10:14:39","slug":"consulado-de-dinamarca-en-jacksonville-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-dinamarca-en-jacksonville-estados-unidos\/","title":{"rendered":"Consulado de Dinamarca en Jacksonville, Estados Unidos"},"content":{"rendered":"<div id=\"trave-2142498944\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado dan\u00e9s en Jacksonville, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nOrange Park, FL 32073<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Larry Joe Warren, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00-16.00<\/p>\n<div id=\"trave-563337492\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado dan\u00e9s en Jacksonville, Estados Unidos Direcci\u00f3n: Orange Park, FL 32073 Estados Unidos Embajador: Mr Larry Joe Warren, C\u00f3nsul Honorario Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina: 09.00-16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13177,15205,13136,13059],"tags":[12978],"class_list":["post-134075","post","type-post","status-publish","format-standard","hentry","category-consulados-daneses","category-consulados-en-estados-unidos","category-dinamarca","category-estados-unidos","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134075"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=134075"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/134075\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=134075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=134075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=134075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}