{"id":133993,"date":"2019-09-01T10:13:45","date_gmt":"2019-09-01T10:13:45","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-argentina-en-atlanta-estados-unidos\/"},"modified":"2019-09-01T10:13:45","modified_gmt":"2019-09-01T10:13:45","slug":"consulado-general-de-argentina-en-atlanta-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-argentina-en-atlanta-estados-unidos\/","title":{"rendered":"Consulado General de Argentina en Atlanta, Estados Unidos"},"content":{"rendered":"<div id=\"trave-759172752\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado argentino en Atlanta, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n245 Peachtree Center Avenue, NE, Suite 2450<br \/>\nAtlanta, GA 30303<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Jorge Lopez Menardi, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) 404 880 0805<br \/>\n<strong>Fax:<\/strong> (+1) 404 880 0806<br \/>\n<strong>Email:<\/strong> catla@cancilleria.gob.ar<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 14.00<\/p>\n<div id=\"trave-1317724056\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado argentino en Atlanta, Estados Unidos Direcci\u00f3n: 245 Peachtree Center Avenue, NE, Suite 2450 Atlanta, GA 30303 Estados Unidos Embajador: Mr Jorge Lopez Menardi, C\u00f3nsul General Tel\u00e9fono: (+1) 404 880 0805 Fax: (+1) 404 880 0806 Email: catla@cancilleria.gob.ar Sitio web: Horas de oficina: 09.00 a 14.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4815,13707,15206,13059],"tags":[12988],"class_list":["post-133993","post","type-post","status-publish","format-standard","hentry","category-argentina","category-consulado-general-argentino","category-consulado-general-en-estados-unidos","category-estados-unidos","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133993"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=133993"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133993\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=133993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=133993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=133993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}