{"id":133947,"date":"2019-09-01T10:13:21","date_gmt":"2019-09-01T10:13:21","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-francia-en-austin-estados-unidos\/"},"modified":"2019-09-01T10:13:21","modified_gmt":"2019-09-01T10:13:21","slug":"consulado-de-francia-en-austin-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-francia-en-austin-estados-unidos\/","title":{"rendered":"Consulado de Francia en Austin, Estados Unidos"},"content":{"rendered":"<div id=\"trave-1309347725\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado franc\u00e9s en Austin, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nAustin, TX<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1868873884\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado franc\u00e9s en Austin, Estados Unidos Direcci\u00f3n: Austin, TX Estados Unidos Embajador: Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15205,13518,13059,13000],"tags":[12978],"class_list":["post-133947","post","type-post","status-publish","format-standard","hentry","category-consulados-en-estados-unidos","category-consulados-franceses","category-estados-unidos","category-francia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133947"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=133947"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133947\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=133947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=133947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=133947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}