{"id":133906,"date":"2019-09-01T10:12:57","date_gmt":"2019-09-01T10:12:57","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-uruguay-en-chicago-estados-unidos\/"},"modified":"2019-09-01T10:12:57","modified_gmt":"2019-09-01T10:12:57","slug":"consulado-general-de-uruguay-en-chicago-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-uruguay-en-chicago-estados-unidos\/","title":{"rendered":"Consulado General de Uruguay en Chicago, Estados Unidos"},"content":{"rendered":"<div id=\"trave-561368317\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado uruguayo en Chicago, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n875 North Michigan Ave., Suite 1318<br \/>\nChicago, IL 60611<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Beraldo Roque Nicola Flaniguen, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) (312) 642.34.30<br \/>\n<strong>Fax:<\/strong> (+1) (312) 642.34.70<br \/>\n<strong>Email:<\/strong> cgchicago@mrree.gub.uy<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1086404300\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado uruguayo en Chicago, Estados Unidos Direcci\u00f3n: 875 North Michigan Ave., Suite 1318 Chicago, IL 60611 Estados Unidos Embajador: Beraldo Roque Nicola Flaniguen, C\u00f3nsul General Tel\u00e9fono: (+1) (312) 642.34.30 Fax: (+1) (312) 642.34.70 Email: cgchicago@mrree.gub.uy Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15206,13586,13059,6840],"tags":[12988],"class_list":["post-133906","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-estados-unidos","category-consulado-general-uruguayo","category-estados-unidos","category-uruguay","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133906"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=133906"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133906\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=133906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=133906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=133906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}