{"id":133773,"date":"2019-09-01T10:11:30","date_gmt":"2019-09-01T10:11:30","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-burkina-faso-en-nueva-orleans-estados-unidos\/"},"modified":"2019-09-01T10:11:30","modified_gmt":"2019-09-01T10:11:30","slug":"consulado-de-burkina-faso-en-nueva-orleans-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-burkina-faso-en-nueva-orleans-estados-unidos\/","title":{"rendered":"Consulado de Burkina Faso en Nueva Orleans, Estados Unidos"},"content":{"rendered":"<div id=\"trave-3893291633\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Burkinese en Nueva Orleans, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n650 Poydras Street, Suite 1250<br \/>\nNew Orleans, LA 70130<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr William Raymond Manning, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) (504) 412-2000<br \/>\n<strong>Fax:<\/strong> (+1) (504) 412-2001<br \/>\n<strong>Email:<\/strong> wmanning@manningarchitects.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2668286031\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Burkinese en Nueva Orleans, Estados Unidos Direcci\u00f3n: 650 Poydras Street, Suite 1250 New Orleans, LA 70130 Estados Unidos Embajador: Mr William Raymond Manning, C\u00f3nsul Honorario Tel\u00e9fono: (+1) (504) 412-2000 Fax: (+1) (504) 412-2001 Email: wmanning@manningarchitects.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5046,13786,15205,13059],"tags":[12978],"class_list":["post-133773","post","type-post","status-publish","format-standard","hentry","category-burkina-faso","category-consulados-de-burkinese","category-consulados-en-estados-unidos","category-estados-unidos","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133773"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=133773"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133773\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=133773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=133773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=133773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}