{"id":133599,"date":"2019-09-01T10:09:40","date_gmt":"2019-09-01T10:09:40","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-bolivia-en-nueva-york-estados-unidos\/"},"modified":"2019-09-01T10:09:40","modified_gmt":"2019-09-01T10:09:40","slug":"consulado-general-de-bolivia-en-nueva-york-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-bolivia-en-nueva-york-estados-unidos\/","title":{"rendered":"Consulado General de Bolivia en Nueva York, Estados Unidos"},"content":{"rendered":"<div id=\"trave-577928767\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Bolivia en Nueva York, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n800 Second Avenue, Suite # 430<br \/>\nNueva York, NY 10017<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Alvaro Rodrigo Pinilla Romero, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) (212) 687-0530<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> consulado.bolivia.ny@gmail.com<br \/>\n<strong>Sitio web:<\/strong> www.bolivianyc.org<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2498835362\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Bolivia en Nueva York, Estados Unidos Direcci\u00f3n: 800 Second Avenue, Suite # 430 Nueva York, NY 10017 Estados Unidos Embajador: Alvaro Rodrigo Pinilla Romero, C\u00f3nsul General Tel\u00e9fono: (+1) (212) 687-0530 Fax: Email: consulado.bolivia.ny@gmail.com Sitio web: www.bolivianyc.org Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4972,14005,15206,13059],"tags":[12988],"class_list":["post-133599","post","type-post","status-publish","format-standard","hentry","category-bolivia","category-consulado-general-boliviano","category-consulado-general-en-estados-unidos","category-estados-unidos","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133599"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=133599"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133599\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=133599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=133599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=133599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}