{"id":133392,"date":"2019-09-01T10:07:14","date_gmt":"2019-09-01T10:07:14","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-filipinas-en-nueva-orleans-estados-unidos\/"},"modified":"2019-09-01T10:07:14","modified_gmt":"2019-09-01T10:07:14","slug":"consulado-de-filipinas-en-nueva-orleans-estados-unidos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-filipinas-en-nueva-orleans-estados-unidos\/","title":{"rendered":"Consulado de Filipinas en Nueva Orleans, Estados Unidos"},"content":{"rendered":"<div id=\"trave-323121970\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Filipinas en Nueva Orleans, Estados Unidos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n6660 Riverside Dr., Suite 102<br \/>\nMetairie, LA 70003<br \/>\nEstados Unidos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Roberto Gurmot Romero, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) 504-533-9822<br \/>\n(+1) 504-914-1032<br \/>\n<strong>Fax:<\/strong> (+1) 504-533-9822<br \/>\n<strong>Email:<\/strong> philhoncon.la@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Martes-viernes: 10.00-15.00<\/p>\n<div id=\"trave-2215668955\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Filipinas en Nueva Orleans, Estados Unidos Direcci\u00f3n: 6660 Riverside Dr., Suite 102 Metairie, LA 70003 Estados Unidos Embajador: Mr Roberto Gurmot Romero, C\u00f3nsul Honorario Tel\u00e9fono: (+1) 504-533-9822 (+1) 504-914-1032 Fax: (+1) 504-533-9822 Email: philhoncon.la@gmail.com Sitio web: Horas de oficina: Martes-viernes: 10.00-15.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13196,15205,13059,13195],"tags":[12978],"class_list":["post-133392","post","type-post","status-publish","format-standard","hentry","category-consulados-de-filipinas","category-consulados-en-estados-unidos","category-estados-unidos","category-filipinas","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133392"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=133392"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133392\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=133392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=133392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=133392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}