{"id":133010,"date":"2019-09-01T10:00:24","date_gmt":"2019-09-01T10:00:24","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-polonia-en-belfast-reino-unido\/"},"modified":"2019-09-01T10:00:24","modified_gmt":"2019-09-01T10:00:24","slug":"consulado-general-de-polonia-en-belfast-reino-unido","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-polonia-en-belfast-reino-unido\/","title":{"rendered":"Consulado General de Polonia en Belfast, Reino Unido"},"content":{"rendered":"<div id=\"trave-4061644148\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Polonia en Belfast, Reino Unido<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nBT2 7AF Belfast<br \/>\nReino Unido<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+44) 788 071 2909<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2857121424\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Polonia en Belfast, Reino Unido Direcci\u00f3n: BT2 7AF Belfast Reino Unido Embajador: Tel\u00e9fono: (+44) 788 071 2909 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13742,15181,13263,13069],"tags":[12988],"class_list":["post-133010","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-polonia","category-consulado-general-en-reino-unido","category-polonia","category-reino-unido","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133010"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=133010"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/133010\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=133010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=133010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=133010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}