{"id":132219,"date":"2019-09-01T09:43:24","date_gmt":"2019-09-01T09:43:24","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-eslovenia-en-odessa-ucrania\/"},"modified":"2019-09-01T09:43:24","modified_gmt":"2019-09-01T09:43:24","slug":"consulado-de-eslovenia-en-odessa-ucrania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-eslovenia-en-odessa-ucrania\/","title":{"rendered":"Consulado de Eslovenia en Odessa, Ucrania"},"content":{"rendered":"<div id=\"trave-3365039841\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado esloveno en Odessa, Ucrania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCalle Bozhenko 19<br \/>\n65098 Odessa<br \/>\nUcrania<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Vladislav Borisovich Burda, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+380) 482 305 484<br \/>\n(+380) 67 320 1406<br \/>\n<strong>Fax:<\/strong> (+380) 482 305 494<br \/>\n<strong>Email:<\/strong> slovenia.odessa@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1134153639\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado esloveno en Odessa, Ucrania Direcci\u00f3n: Calle Bozhenko 19 65098 Odessa Ucrania Embajador: Vladislav Borisovich Burda, C\u00f3nsul Honorario Tel\u00e9fono: (+380) 482 305 484 (+380) 67 320 1406 Fax: (+380) 482 305 494 Email: slovenia.odessa@gmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15172,13576,13180,13254],"tags":[12978],"class_list":["post-132219","post","type-post","status-publish","format-standard","hentry","category-consulados-en-ucrania","category-consulados-eslovenos","category-eslovenia","category-ucrania","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/132219"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=132219"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/132219\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=132219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=132219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=132219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}